{"id":1169,"date":"2022-02-15T21:50:07","date_gmt":"2022-02-15T21:50:07","guid":{"rendered":"https:\/\/thelittlerstravel.com\/?p=1169"},"modified":"2022-02-15T21:50:20","modified_gmt":"2022-02-15T21:50:20","slug":"descubre-shanghai-en-3-dias","status":"publish","type":"post","link":"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/","title":{"rendered":"Descubre Shanghai en 3 d\u00edas"},"content":{"rendered":"<p>Este fue el comienzo de nuestra luna de miel. A Josh le hac\u00eda mucha ilusi\u00f3n ir a Asia y yo acced\u00ed, pero solo si lo visit\u00e1bamos en un crucero. Nuestro viaje dur\u00f3 poco menos de un mes y visitamos: China, Corea del Sur, la isla de Jeju, Jap\u00f3n, Taiw\u00e1n y Hong Kong.<br>China es el lugar con m\u00e1s diferencia cultural que hemos visitado y como cuando esto pasa, hay varias cosas que te encantan y otras que no tanto.<\/p>\n\n\n\n<p>Le\u00edmos decenas de blogs para preparar el tour de Shanghai y todos ellos se ce\u00f1\u00edan a enumerar los puntos a visitar, pero nosotros consideramos que nos hubiera encantado haber le\u00eddo, aprendido y haber sabido mucho m\u00e1s de la cultura antes de haber llegado. Creemos que esto nos hubiera adelantado y prevenido varias situaciones y es por eso, que te queremos contar todo tal y como fue, con pelos y se\u00f1ales para que cuando visites estas magn\u00edficas tierras, est\u00e9s preparado y con la mente lista para disfrutarlo al m\u00e1ximo.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Nuestro Viaje<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97e16157599\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #444444;color:#444444\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #444444;color:#444444\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97e16157599\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Dia_1_en_Shanghai_%E2%80%93_Vuelo_y_Disneyland_Shanghai\" >D\u00eda 1 en Shanghai &#8211; Vuelo y Disneyland Shanghai<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Viaje\" >Viaje<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Llegada_a_Shanghai\" >Llegada a Shanghai<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Shanghai_Disney_Resort\" >Shanghai Disney Resort<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Dia_2_en_Shanghai_%E2%80%93_Visitando_la_ciudad_de_Shanghai\" >D\u00eda 2 en Shanghai \u2013 Visitando la ciudad de Shanghai<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Tour_de_la_ciudad\" >Tour de la ciudad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#El_Mercado_de_Falsificaciones\" >El Mercado de Falsificaciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Torre_Oriental_Pearl\" >Torre Oriental Pearl<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Dia_3_en_Shanghai_%E2%80%93_Shanghai_City_Crucero\" >D\u00eda 3 en Shanghai &#8211; Shanghai City &amp; Crucero<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Informacion_Util\" >Informaci\u00f3n \u00datil<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/thelittlerstravel.com\/es\/2022\/02\/descubre-shanghai-en-3-dias\/#Consejos\" >Consejos<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"dia-1-en-shanghai-vuelo-y-disneyland-shanghai\"><span class=\"ez-toc-section\" id=\"Dia_1_en_Shanghai_%E2%80%93_Vuelo_y_Disneyland_Shanghai\"><\/span>D\u00eda 1 en Shanghai &#8211; Vuelo y Disneyland Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"viaje\"><span class=\"ez-toc-section\" id=\"Viaje\"><\/span><strong>Viaje<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Llegamos a <strong>Londres Heathrow<\/strong> con mucha antelaci\u00f3n, as\u00ed que, como siempre hacemos cuando esto sucede, fuimos a la sala VIP donde podemos comer, beber y repetir.<br>Esta es una muy buena opci\u00f3n cuando tienes mucho tiempo y hambre, ya que en la sala VIP puedes comer y beber todo lo que quieras mientras disfrutas de una buena se\u00f1al wifi y c\u00f3modos sof\u00e1s.<br>Depende del aeropuerto, pero nosotros solo accedemos cuando est\u00e1n sobre los 30\u20ac por cabeza, a este precio, consideramos que si tenemos que parar a comer en el aeropuerto y despu\u00e9s a tomar un caf\u00e9 y comprar una revista, en muchas ocasiones terminamos pagando m\u00e1s.<\/p>\n\n\n\n<p>En esta situaci\u00f3n y aprovechando el hecho de que era nuestra luna de miel, preguntamos en varias ocasiones y a varios miembros del personal, si nos pod\u00edan mejorar la categor\u00eda de nuestro <strong>vuelo<\/strong> y volar en Business, pero de forma gratuita, por supuesto.<br>Siempre leemos que los viajeros suelen recibir una mejor categor\u00eda solo por preguntar educadamente, sin embargo, podemos decir abiertamente que nunca hemos estado entre esos pasajeros afortunados y que esta vez, no fue diferente.<br>En lugar de eso, ten\u00edamos a un reci\u00e9n nacido delante y a dos ni\u00f1os de seis a\u00f1os detr\u00e1s de nosotros. Karma. Solo porque consideramos que merec\u00edamos un trato especial porque era nuestra luna de miel. Karma delante y detr\u00e1s.<\/p>\n\n\n\n<p>Pero sin perder la esperanza, Josh pregunt\u00f3 por \u00faltima vez a los azafatos del avi\u00f3n y esta vez, en lugar del \u201clo siento caballero\u201d, nos dieron precios: \u00a32000 o \u00a36000 dependiendo de la categor\u00eda elegida.<br>Despu\u00e9s de eso, nos pusimos c\u00f3modos en nuestros asientos baratos y dormimos durante 1 hora en la totalidad del viaje.<\/p>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"llegada-a-shanghai\"><span class=\"ez-toc-section\" id=\"Llegada_a_Shanghai\"><\/span>Llegada a Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Aterrizamos en Shanghai a primera hora de la ma\u00f1ana y nos subimos al transfer que nos llev\u00f3 durante 1 hora hasta nuestro <strong>hotel Radisson Blu New World<\/strong> en el centro de la ciudad.<br>La habitaci\u00f3n estaba genial, era grande y ten\u00eda unas vistas incre\u00edbles, pero desafortunadamente no pudimos disfrutarlas mucho debido a la cantidad de niebla provocada por la contaminaci\u00f3n que cubre constantemente la ciudad.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-1024x1024.jpg\" alt=\"Views from Hotel\" class=\"wp-image-1195\" width=\"353\" height=\"353\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-1024x1024.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-300x300.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-150x150.jpg 150w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-768x768.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-1536x1536.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-2048x2048.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-1920x1920.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-600x600.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-800x800.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-278x278.jpg 278w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1793-247x247.jpg 247w\" sizes=\"auto, (max-width: 353px) 100vw, 353px\" \/><figcaption>Vistas desde el hotel<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"shanghai-disney-resort\"><span class=\"ez-toc-section\" id=\"Shanghai_Disney_Resort\"><\/span>Shanghai Disney Resort<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Nuestro primer d\u00eda lo pasamos visitando Shanghai Disney Resort, as\u00ed que nos subimos al <strong>metro<\/strong> y por 12 yuanes (unos 1,5 \u20ac) nos llev\u00f3 directamente hasta all\u00ed.<\/p>\n\n\n\n<p>Aqu\u00ed es donde nos dimos cuenta por primera vez de que:<br>1 &#8211; Nadie entiende ni habla ingl\u00e9s.<br>2 &#8211; Todos miran a los occidentales. Es una mirada constante que no cesa, aunque mires de vuelta. Pero hay que tener en cuenta que para ellos, esto no es de mala educaci\u00f3n. Ellos se sienten curiosos porque no es com\u00fan ver a occidentales e incluso muchos lugare\u00f1os te sacar\u00e1n fotos. Nos sentimos tan famosos como Justin Bieber y nos hicieron m\u00e1s fotos que en el d\u00eda de nuestra boda.<\/p>\n\n\n\n<p>Estoy casi segura de que la mitad de Shanghai tiene mi foto en sus m\u00f3viles, al principio le ped\u00eda a Josh que se colocara delante de m\u00ed, pero la gente le rodeaba o empujaba para sacarme una foto, as\u00ed que al final, decid\u00ed otorgar mis derechos de imagen a la Rep\u00fablica Popular de China.<\/p>\n\n\n\n<p>Finalmente, llegamos a <strong>Disneyland Shanghai<\/strong>, donde pagamos 800 yuanes por nuestras dos entradas (unos 100 \u20ac).<\/p>\n\n\n\n<p>Vimos todos los desfiles y disfrutamos escuchando todas las canciones de Disney en chino.<\/p>\n\n\n\n<p>La mejor atracci\u00f3n sin duda fue Tron, y aunque est\u00e1bamos exhaustos, lo pasamos de maravilla, como siempre lo hacemos cuando visitamos un parque tem\u00e1tico de Disney.<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel has-responsive-height\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg has-aligned-cells\" data-flickity=\"{&quot;autoPlay&quot;:false,&quot;draggable&quot;:true,&quot;pageDots&quot;:false,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;left&quot;,&quot;pauseAutoPlayOnHover&quot;:false,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:true}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-768x1024.jpg\" alt=\"Sonia Shanghai Disney Resort\" data-id=\"1183\" data-link=\"https:\/\/thelittlerstravel.com\/img_1821\/\" class=\"wp-image-1183\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1821-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1010\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-1010x1024.jpg\" alt=\"Mulan in Disneyland Shanghai\" data-id=\"924\" data-link=\"https:\/\/thelittlerstravel.com\/2020\/05\/explore-shanghai-in-3-days\/img_1837\/\" class=\"wp-image-924\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-1010x1024.jpg 1010w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-296x300.jpg 296w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-768x779.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-600x608.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669-800x811.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1837-scaled-e1588421645669.jpg 1420w\" sizes=\"auto, (max-width: 1010px) 100vw, 1010px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-1024x769.jpg\" alt=\"Josh and Sonia Shanghai Disney Resort\" data-id=\"1182\" data-link=\"https:\/\/thelittlerstravel.com\/img_1155\/\" class=\"wp-image-1182\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-1024x769.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-300x225.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-768x577.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-1536x1154.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-2048x1539.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-1920x1442.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-600x451.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-800x601.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-141x106.jpg 141w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-380x285.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1155-247x186.jpg 247w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-768x1024.jpg\" alt=\"Shanghai Disney Resort\" data-id=\"1184\" data-link=\"https:\/\/thelittlerstravel.com\/img_1874\/\" class=\"wp-image-1184\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1874-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-1024x769.jpg\" alt=\"Josh and Sonia Shanghai Disney Resort\" data-id=\"1173\" data-link=\"https:\/\/thelittlerstravel.com\/es\/2020\/05\/descubre-shanghai-en-3-dias\/josh-and-sonia-disney-shanghai\/\" class=\"wp-image-1173\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-1024x769.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-300x225.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-768x577.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-1536x1154.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-2048x1539.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-1920x1442.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-600x451.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-800x601.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-141x106.jpg 141w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-380x285.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Josh-and-Sonia-Disney-Shanghai-247x186.jpg 247w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>De vuelta al hotel, paramos en una de las tiendas de la estaci\u00f3n de metro y compramos sushi, dos tartaletas y helado y cenamos en nuestra habitaci\u00f3n de hotel.<\/p>\n\n\n\n<h2 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"dia-2-en-shanghai-visitando-la-ciudad-de-shanghai\"><span class=\"ez-toc-section\" id=\"Dia_2_en_Shanghai_%E2%80%93_Visitando_la_ciudad_de_Shanghai\"><\/span>D\u00eda 2 en Shanghai \u2013 Visitando la ciudad de Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Reservamos nuestro crucero, vuelos, hotel, traslados &#8230; con una agencia de viajes llamada<strong> Iglu Cruises <\/strong>del Reino Unido, una compa\u00f1\u00eda que hemos usado varias veces y que nos encanta porque se encargan de organizarlo todo, as\u00ed que t\u00fa solo te tienes que preocupar por disfrutar de cada segundo.<\/p>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"tour-de-la-ciudad\"><span class=\"ez-toc-section\" id=\"Tour_de_la_ciudad\"><\/span>Tour de la ciudad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Incluido en nuestro paquete, ten\u00edamos un tour para aprender m\u00e1s sobre la ciudad de Shanghai.<br>Estuvimos esperando durante treinta minutos a un grupo que no llegaba y cuando decidimos irnos sin ellos, la gu\u00eda solt\u00f3 un comentario tan racista, que nos dej\u00f3 a todos sorbiendo el t\u00e9 matcha, calladitos y port\u00e1ndonos bien.<\/p>\n\n\n\n<p>Durante el recorrido, visitamos el fant\u00e1stico <strong>Barrio Yuyuan<\/strong> y los Jardines de Yuyuan, que son una combinaci\u00f3n de casas tradicionales, estanques y arquitectura t\u00edpica.<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel has-responsive-height\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg has-aligned-cells\" data-flickity=\"{&quot;autoPlay&quot;:false,&quot;draggable&quot;:true,&quot;pageDots&quot;:false,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;left&quot;,&quot;pauseAutoPlayOnHover&quot;:false,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:true}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-1024x683.jpg\" alt=\"Yuyuan Gardens\" data-id=\"1192\" data-link=\"https:\/\/thelittlerstravel.com\/yuyuan-5\/\" class=\"wp-image-1192\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-5-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-1024x683.jpg\" alt=\"Yuyuan Gardens 2\" data-id=\"1189\" data-link=\"https:\/\/thelittlerstravel.com\/yuyuan-juntos\/\" class=\"wp-image-1189\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-juntos-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-1024x683.jpg\" alt=\"Yuyuan Gardens 3\" data-id=\"1185\" data-link=\"https:\/\/thelittlerstravel.com\/barrio-yuyuan\/\" class=\"wp-image-1185\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Barrio-yuyuan-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-1024x683.jpg\" alt=\"Yuyuan Dragon\" data-id=\"1187\" data-link=\"https:\/\/thelittlerstravel.com\/yuyu\/\" class=\"wp-image-1187\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyu-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-1024x1024.jpg\" alt=\"Yuyuan Gardens\" data-id=\"929\" data-link=\"https:\/\/thelittlerstravel.com\/2020\/05\/explore-shanghai-in-3-days\/img_2414\/\" class=\"wp-image-929\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-1024x1024.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-300x300.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-150x150.jpg 150w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-768x768.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-1536x1536.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-600x600.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-800x800.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-278x278.jpg 278w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653-247x247.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2414-scaled-e1588443322653.jpg 1709w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-683x1024.jpg\" alt=\"Yuyuan Lion\" data-id=\"1188\" data-link=\"https:\/\/thelittlerstravel.com\/yuyuan-6\/\" class=\"wp-image-1188\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/yuyuan-6-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-1024x683.jpg\" alt=\"Yuyuan House\" data-id=\"1193\" data-link=\"https:\/\/thelittlerstravel.com\/yuyuan\/\" class=\"wp-image-1193\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-768x1024.jpg\" alt=\"Yuyuan Doorway\" data-id=\"1186\" data-link=\"https:\/\/thelittlerstravel.com\/img_0039\/\" class=\"wp-image-1186\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-800x1066.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_0039-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-1024x683.jpg\" alt=\"Yuyuan Gardens 4\" data-id=\"1191\" data-link=\"https:\/\/thelittlerstravel.com\/yuyuan-4\/\" class=\"wp-image-1191\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Yuyuan-4-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><\/div><\/div><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Un paseo por Yuyuan<\/figcaption><\/div>\n\n\n\n<p>Aqu\u00ed es uno de los \u00fanicos lugares, si no el \u00fanico, en todo Shanghai donde puedes comprar souvenirs y postales, as\u00ed que aseg\u00farate de no irte sin ellos!<\/p>\n\n\n\n<p>Luego nos dirigimos hacia <strong>el Bund<\/strong>, que es un paseo mar\u00edtimo con esculturas, jardines y excelentes vistas de la ciudad.<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel has-responsive-height\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg has-aligned-cells\" data-flickity=\"{&quot;autoPlay&quot;:false,&quot;draggable&quot;:true,&quot;pageDots&quot;:false,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;left&quot;,&quot;pauseAutoPlayOnHover&quot;:false,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:true}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-683x1024.jpg\" alt=\"Josh and Sonia The Bund\" data-id=\"1213\" data-link=\"https:\/\/thelittlerstravel.com\/the-bond\/\" class=\"wp-image-1213\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/the-bond-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-1024x1024.jpg\" alt=\"The Oriental Pearl\" data-id=\"918\" data-link=\"https:\/\/thelittlerstravel.com\/2020\/05\/explore-shanghai-in-3-days\/img_7904\/\" class=\"wp-image-918\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-1024x1024.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-300x300.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-150x150.jpg 150w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-768x768.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-1536x1536.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-600x600.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-800x800.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-278x278.jpg 278w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632-247x247.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_7904-scaled-e1588443189632.jpg 1824w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-768x1024.jpg\" alt=\"Sonia Bund\" data-id=\"1196\" data-link=\"https:\/\/thelittlerstravel.com\/img_1974\/\" class=\"wp-image-1196\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_1974-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>Con vistas a los modernos rascacielos, como el Oriental Pearl, la Torre de Shanghai y el Centro Financiero Mundial de Shanghai.<\/p>\n\n\n\n<p>En ese mismo paseo, tambi\u00e9n nos llevaron a visitar una <strong>f\u00e1brica de perlas y jade<\/strong> donde compr\u00e9 por un precio excesivo (estoy segura de ello aunque encantada con lo que compr\u00e9), un anillo y unos pendientes y Josh compr\u00f3 un drag\u00f3n de jade.<\/p>\n\n\n\n<p>Terminamos nuestro recorrido en la <strong>Concesi\u00f3n Francesa<\/strong>, que es una excelente \u00e1rea para comer o cenar.<\/p>\n\n\n\n<p>Despu\u00e9s del recorrido, comenzamos el tour que hab\u00edamos planeado nosotros mismos, y el primer lugar que visitamos fue <strong>Fuixing Park<\/strong>, donde supuestamente, a parte de un gran parque, hab\u00edamos le\u00eddo que hab\u00eda un pub llamado Pub 97 con una pecera con tiburones. Miramos y caminamos por todas partes, pero no pudimos encontrarlo de ninguna manera.<\/p>\n\n\n\n<p>Nos subimos al metro y fuimos a nuestra siguiente parada, el <strong>Templo Longshan<\/strong>. La estaci\u00f3n de metro estaba siendo renovada, as\u00ed que terminamos saliendo a un descampado gigante con campo a un lado y una pared al otro.<br>Varias personas con motos pasaban y se paraban para mirarnos curiosamente y finalmente y de repente, llegamos a la calle principal que nos llev\u00f3 al templo.<br>Este estaba repleto de budas y nos encantaron cada uno de sus espacios.<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel has-responsive-height\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg has-aligned-cells\" data-flickity=\"{&quot;autoPlay&quot;:false,&quot;draggable&quot;:true,&quot;pageDots&quot;:false,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;left&quot;,&quot;pauseAutoPlayOnHover&quot;:false,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:true}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-768x1024.jpg\" alt=\"\" data-id=\"1200\" data-link=\"https:\/\/thelittlerstravel.com\/longshan7\/\" class=\"wp-image-1200\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/LONGSHAN7-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-1024x683.jpg\" alt=\"\" data-id=\"1203\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-3\/\" class=\"wp-image-1203\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-3-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-769x1024.jpg\" alt=\"\" data-id=\"1197\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-6\/\" class=\"wp-image-1197\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-769x1024.jpg 769w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-768x1022.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-1154x1536.jpg 1154w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-1539x2048.jpg 1539w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-1442x1920.jpg 1442w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-600x799.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-800x1065.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-6-278x371.jpg 278w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-768x1024.jpg\" alt=\"\" data-id=\"1199\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-9\/\" class=\"wp-image-1199\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-9-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-1024x683.jpg\" alt=\"\" data-id=\"1205\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-4\/\" class=\"wp-image-1205\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-4-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-683x1024.jpg\" alt=\"\" data-id=\"1206\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-5\/\" class=\"wp-image-1206\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-5-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-768x1024.jpg\" alt=\"\" data-id=\"1204\" data-link=\"https:\/\/thelittlerstravel.com\/longshan-10\/\" class=\"wp-image-1204\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-10-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-1024x683.jpg\" alt=\"\" data-id=\"1212\" data-link=\"https:\/\/thelittlerstravel.com\/templo-longshan\/\" class=\"wp-image-1212\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-longshan-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-683x1024.jpg\" alt=\"\" data-id=\"1207\" data-link=\"https:\/\/thelittlerstravel.com\/longshan\/\" class=\"wp-image-1207\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/longshan-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-768x1024.jpg\" alt=\"\" data-id=\"919\" data-link=\"https:\/\/thelittlerstravel.com\/2020\/05\/explore-shanghai-in-3-days\/img_2046\/\" class=\"wp-image-919\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-278x371.jpg 278w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/IMG_2046-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"el-mercado-de-falsificaciones\"><span class=\"ez-toc-section\" id=\"El_Mercado_de_Falsificaciones\"><\/span>El Mercado de Falsificaciones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Una vez terminamos la visita al templo, decidimos ir al famoso mercado de las falsificaciones ubicado en la estaci\u00f3n de <strong>metro &#8220;Shanghai Technology &amp; Science Museum&#8221;.<\/strong><br>Antes de nuestro viaje, pasamos bastante tiempo tratando de encontrar el mejor mercado de falsificaciones ya que hay varios, y fue bastante dif\u00edcil porque no entend\u00edamos d\u00f3nde estaban exactamente ubicados, sin embargo, cuando llegues, sabr\u00e1s que est\u00e1s en el lugar correcto.<\/p>\n\n\n\n<p>Es un laberinto lleno de tiendas y gente comprando y vendiendo art\u00edculos de falsificaci\u00f3n de alta calidad.<br>Justo en la entrada de este &#8220;centro comercial&#8221;, ser\u00e1s recibido por la frase que te acompa\u00f1ar\u00e1 durante todo el tiempo que pases en ese mundo subterr\u00e1neo, bastante sucio, oscuro y lleno de vida: Bag or watch? (\u00bfbolso o reloj?)<\/p>\n\n\n\n<p>En el momento en que respondes: S\u00ed! Un chico te guiar\u00e1 por todo el laberinto, como una especie de personal shopper que te llevar\u00e1 hasta lo que est\u00e9s buscando, si quieres un reloj, te llevar\u00e1 a una tienda de relojes donde probablemente obtenga una comisi\u00f3n por cada venta y al terminar, lo mismo para comprar bolsos, tel\u00e9fonos m\u00f3viles, ropa, bufandas, zapatillas &#8230; y cualquier otra cosa que se te ocurra, la podr\u00e1s encontrar en este lugar.<\/p>\n\n\n\n<p>Durante m\u00e1s de 2 horas fuimos algo as\u00ed como la Pretty Woman ilegal de Shanghai y estuvimos negociando como nunca antes hab\u00edamos negociado.<\/p>\n\n\n\n<p>Josh quer\u00eda un reloj de marca de falsificaci\u00f3n y cuando lo encontr\u00f3, el precio de partida era de 3250 yuanes (aproximadamente 420 \u20ac).<br>Despu\u00e9s de una intensa negociaci\u00f3n en la que el vendedor lo cog\u00eda y estiraba del brazo, el precio segu\u00eda sin ser lo que Josh estaba dispuesto a pagar, as\u00ed que decidimos salir de la tienda y finalmente, fue entonces cuando el vendedor nos grit\u00f3 la oferta final mientras nosotros and\u00e1bamos por el pasillo.<br>Josh se dio la vuelta, volvi\u00f3 a la tienda y termin\u00f3 comprando un reloj de lujo de excelente calidad (con la magn\u00edfica caracter\u00edstica de que cada mes tiene 39 d\u00edas), por 200 yuanes (unos 25 \u20ac).<\/p>\n\n\n\n<p>Entonces lleg\u00f3 mi turno, yo quer\u00eda comprarme un bolso, as\u00ed que nuestro asistente de compras nos llev\u00f3 a otra tienda, pero no me gustaban porque se notaba que eran falsos y de mala calidad.<br>As\u00ed que el vendedor se acerc\u00f3 a m\u00ed y me pregunt\u00f3 que qu\u00e9 estaba buscando, le expliqu\u00e9 que estaba buscando grandes marcas, bolsos de dise\u00f1ador con dise\u00f1os de \u00faltimas temporadas y de buena calidad y no se hable m\u00e1s!<br>Nos dijo que lo sigui\u00e9ramos a trav\u00e9s de ese laberinto de tiendas hasta llegar a una persiana de metal negro, la abri\u00f3 y mientras esperaba pacientemente a que me secuestraran para venderme a trozos, abri\u00f3 otra puerta que era completamente invisible a simple vista y que te llevaba directamente a una boutique de bolsos llena de gente, muy limpia, con espejos y con bolsos de dise\u00f1o bien presentados y expuestos y de gran calidad. All\u00ed compr\u00e9 un bolso por 200 yuanes.<\/p>\n\n\n\n<p>Terminamos nuestro tour de compras comprando trece bufandas y pa\u00f1uelos de seda de gran calidad y buenas marcas (con su bolsa de marca, etiquetas e incluso factura falsa), todos ellos por 600 yuanes.<\/p>\n\n\n\n<p>\u00a1Podr\u00edamos haber comprado muchas otras cosas que nos encantaban! Abrigos, deportivas, gafas de sol &#8230; pero no quer\u00edamos comprar mucho porque era nuestra primera parada y hab\u00edamos le\u00eddo tambi\u00e9n acerca de los mercados de falsificaciones en Hong Kong, que era el destino final de nuestro crucero.<br>Pero ahora que hemos visitado los dos, podemos decir que los de Hong Kong no tienen nada que ver con los mercados de Shanghai, por lo que si deseas comprar buena calidad a un excelente precio, Shanghai es tu lugar.<\/p>\n\n\n\n<h3 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"torre-oriental-pearl\"><span class=\"ez-toc-section\" id=\"Torre_Oriental_Pearl\"><\/span>Torre Oriental Pearl<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Agotados pero muy contentos con todo lo que hab\u00edamos comprado, decidimos ir a la torre Oriental Pearl a cenar.<\/p>\n\n\n\n<p>Durante las \u00faltimas 24 h solo hab\u00eda estado subsistiendo a base de t\u00e9 de Starbucks porque no pod\u00eda encontrar un lugar para comer, donde estuviera 100% segura de que no iba a comer carne o pescado. Soy vegetariana y fue realmente dif\u00edcil comer en Shanghai porque ni la comida ni los ingredientes sol\u00edan estar indicados y los camareros no respond\u00edan tus dudas, aunque les preguntaras.<br>Eso s\u00ed, estaba feliz de no ser al\u00e9rgica o intolerante a nada, ya que las comidas se habr\u00edan convertido en una ruleta rusa.<\/p>\n\n\n\n<p>As\u00ed que decidimos comer bien al menos una vez durante nuestra estancia en Shanghai, nos arreglamos, cogimos el metro y llegamos al Oriental Pearl buscando el restaurante buffet giratorio con vistas 360\u00baC de la ciudad.<br>En la entrada, hab\u00eda un punto de control de seguridad donde necesit\u00e1bamos dejar nuestro mechero en una caja de cart\u00f3n y luego, ya nos permitieron acceder a una plaza en donde estaba ubicada la Perla Oriental.<\/p>\n\n\n\n<p>Descubrimos, sin saber c\u00f3mo, que necesit\u00e1bamos comprar los tickets antes de acceder al ascensor que nos llevar\u00eda al restaurante en la parte superior.<br>Decidimos probar suerte en recepci\u00f3n, pero por supuesto, la persona detr\u00e1s del mostrador no sab\u00eda hablar ingl\u00e9s ni se mostraba muy interesada en ayudarnos. Es importante, tener en cuenta que, que no te quieran contestar a preguntas, para ellos no se considera un acto de mala educaci\u00f3n. La gu\u00eda tur\u00edstica nos explic\u00f3 que ellos consideran que al muchos habitantes, les ser\u00eda imposible contestar y resolver dudas a todos aquellos que lo pudieran necesitar.<br>As\u00ed que descargamos la aplicaci\u00f3n <strong>Google Translator<\/strong> con la que puedes traducir cualquier texto simplemente con la c\u00e1mara del m\u00f3vil y apuntando con la c\u00e1mara el texto a traducir, vimos que hab\u00eda una opci\u00f3n llamada algo as\u00ed como: ascensor y restaurante. Esperando que la traducci\u00f3n fuera la correcta, nos pusimos de nuevo en la cola.<br>Cuando era nuestro turno, indicamos con el dedo la opci\u00f3n que quer\u00edamos y para variar, la tarjeta de cr\u00e9dito no funcion\u00f3. Por alguna raz\u00f3n, en Shanghai nuestras tarjetas solo funcionaban cuando se introduc\u00eda el chip y no cuando se pasaba la banda magn\u00e9tica.<br>Se lo explicamos con signos a la recepcionista, pero no estuvo por la labor de probarlo y nos indic\u00f3 que nos apart\u00e1ramos para dejar paso a otros clientes.<\/p>\n\n\n\n<p>En este punto y decididos a no dejar pasar la oportunidad de cenar en un sitio tan emblem\u00e1tico, decidimos ir a buscar un cajero autom\u00e1tico para sacar algo de dinero y simplemente pagar con efectivo, ya que consideramos que ser\u00eda la opci\u00f3n m\u00e1s sencilla para todos. As\u00ed que salimos de la torre, de la plaza, pasamos por el punto de control de seguridad y caminamos hasta encontrar un banco y contentos con nuestro dinero en efectivo fuimos a comprar nuestros tickets que costaban unos 45\u20ac por cabeza.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-1024x769.jpg\" alt=\"oriental pearl\" class=\"wp-image-1194\" width=\"474\" height=\"355\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-1024x769.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-300x225.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-768x577.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-1536x1154.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-2048x1539.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-1920x1442.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-600x451.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-800x601.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-141x106.jpg 141w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-380x285.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/oriental-pearl-247x186.jpg 247w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure><\/div>\n\n\n\n<p>Por fin, el ascensor nos subi\u00f3 al restaurante, est\u00e1bamos hambrientos y tambi\u00e9n emocionados de estar all\u00ed y cuando nos asignaron una mesa, fuimos a ver qu\u00e9 hab\u00eda en el buffet.<br>La variedad era enorme, pero nuevamente, ninguno de los platos estaba indicado con los ingredientes ni con lo que eran y puedo asegurarte que a simple vista, y a veces ni prob\u00e1ndolos, se pod\u00eda determinar.<br>Como est\u00e1bamos en la atracci\u00f3n m\u00e1s tur\u00edstica y famosa de Shanghai, le pregunt\u00e9 al camarero detr\u00e1s de una de las mesas del buffet y, nuevamente, no obtuve nada m\u00e1s que una mirada sostenida, as\u00ed que llen\u00e9 mi plato con cacahuetes y disfrut\u00e9 de la cena con cacahuetes m\u00e1s cara de mi vida, pero eso s\u00ed, con unas incre\u00edbles vistas 360\u00baC de la ciudad de Shanghai.<\/p>\n\n\n\n<p>Una vez que terminamos de cenar (fue bastante r\u00e1pido sobretodo para mi) decidimos irnos hacia el hotel, pero no se nos permit\u00edan usar el ascensor ya que dedicaban la bajada como parte de la atracci\u00f3n tur\u00edstica y te obligaban a bajar a pie, visitando todos los pisos con vistas panor\u00e1micas uno por uno.<br>De vuelta al hotel supe que, al menos con lo que a mi respecta, seguir\u00eda bebiendo t\u00e9 de Starbucks durante el resto del tiempo en Shanghai para el desayuno, la comida y la cena.<\/p>\n\n\n\n<h2 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"dia-3-en-shanghai-shanghai-city-crucero\"><span class=\"ez-toc-section\" id=\"Dia_3_en_Shanghai_%E2%80%93_Shanghai_City_Crucero\"><\/span>D\u00eda 3 en Shanghai &#8211; Shanghai City &amp; Crucero<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Este d\u00eda solo ten\u00edamos unas pocas horas para hacer turismo porque nuestro transfer nos recog\u00eda a las 9:45 a.m. y no est\u00e1bamos dispuestos a perder la oportunidad de continuar descubriendo esta ciudad y su cultura, as\u00ed que a las 6 de la ma\u00f1ana nos despertamos, pasamos a por un Starbucks y nos dirigimos al <strong>Templo del Buda de Jade<\/strong> que nos encant\u00f3 e inmediatamente supimos que hab\u00eda valido la pena levantarse temprano.<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel has-responsive-height\"><div class=\"is-cropped coblocks-gallery has-no-alignment has-caption-style-dark has-horizontal-gutter has-lightbox\"><div class=\"has-carousel has-carousel-lrg has-aligned-cells\" data-flickity=\"{&quot;autoPlay&quot;:false,&quot;draggable&quot;:true,&quot;pageDots&quot;:false,&quot;prevNextButtons&quot;:true,&quot;wrapAround&quot;:true,&quot;cellAlign&quot;:&quot;left&quot;,&quot;pauseAutoPlayOnHover&quot;:false,&quot;freeScroll&quot;:false,&quot;arrowShape&quot;:{&quot;x0&quot;:10,&quot;x1&quot;:60,&quot;y1&quot;:50,&quot;x2&quot;:65,&quot;y2&quot;:45,&quot;x3&quot;:20},&quot;thumbnails&quot;:false,&quot;responsiveHeight&quot;:true}\"><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-1024x683.jpg\" alt=\"Jade Buddha Temple\" data-id=\"1209\" data-link=\"https:\/\/thelittlerstravel.com\/templo-del-buda-de-jade-2\/\" class=\"wp-image-1209\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-1024x683.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-300x200.jpg 300w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-768x512.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-1536x1024.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-2048x1365.jpg 2048w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-1920x1280.jpg 1920w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-600x400.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-800x533.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-227x152.jpg 227w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-143x96.jpg 143w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-585x390.jpg 585w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-2-385x257.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-683x1024.jpg\" alt=\"Jade Buddha Temple\" data-id=\"1211\" data-link=\"https:\/\/thelittlerstravel.com\/templo-del-buda-de-jade\/\" class=\"wp-image-1211\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/Templo-del-buda-de-jade-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-723x1024.jpg\" alt=\"Jade Buddha Temple\" data-id=\"1210\" data-link=\"https:\/\/thelittlerstravel.com\/templo-del-buda-de-jade-3\/\" class=\"wp-image-1210\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-723x1024.jpg 723w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-212x300.jpg 212w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-768x1088.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-1084x1536.jpg 1084w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-1446x2048.jpg 1446w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-1356x1920.jpg 1356w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-600x850.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-del-buda-de-jade-3-800x1133.jpg 800w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-683x1024.jpg\" alt=\"Jade Buddha Temple\" data-id=\"1208\" data-link=\"https:\/\/thelittlerstravel.com\/templo-de-buda-jade-4\/\" class=\"wp-image-1208\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-683x1024.jpg 683w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-200x300.jpg 200w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-768x1152.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-1024x1536.jpg 1024w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-1365x2048.jpg 1365w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-1280x1920.jpg 1280w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-600x900.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-de-buda-jade-4-800x1200.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div><div class=\"coblocks-gallery--item\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-768x1024.jpg\" alt=\"Jade Buddha Temple\" data-id=\"1201\" data-link=\"https:\/\/thelittlerstravel.com\/templo-buda-jade\/\" class=\"wp-image-1201\" srcset=\"https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-768x1024.jpg 768w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-225x300.jpg 225w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-1152x1536.jpg 1152w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-1536x2048.jpg 1536w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-1440x1920.jpg 1440w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-600x800.jpg 600w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-800x1067.jpg 800w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-380x507.jpg 380w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-247x330.jpg 247w, https:\/\/thelittlerstravel.com\/wp-content\/uploads\/2020\/05\/templo-buda-jade-278x371.jpg 278w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>De camino al hotel y con tiempo de sobra para el transfer, decidimos bajar en una parada de metro antes de la de nuestro hotel, para poder encontrar una postal que siempre enviamos a nuestra familia.<br>Caminamos durante m\u00e1s de 1 hora en l\u00ednea recta hasta llegar al hotel, \u00e9ramos totalmente inconscientes de cu\u00e1n grande era la ciudad y durante ese tiempo, paramos y preguntamos en varias tiendas, llev\u00e1bamos la palabra escrita en chino en nuestro m\u00f3vil, pero desafortunadamente, no pudimos encontrar ninguna postal.<br>Eso s\u00ed, en una de esas tiendas, encontramos un juego de t\u00e9 s\u00faper bonito que nos cost\u00f3 25 yuanes (3 \u20ac m\u00e1s o menos).<\/p>\n\n\n\n<p>Llegamos al hotel justo a tiempo para ser recogidos por el transfer que nos llev\u00f3 directamente a la Terminal de cruceros para subir al <strong>Celebrity Millenium<\/strong>.<\/p>\n\n\n\n<p>Llegamos muy muy temprano, hab\u00edamos llamado a la compa\u00f1\u00eda de transfers para retrasar nuestro horario de recogida, pero no nos pudieron ayudar porque no hablaban ingl\u00e9s, por lo que fuimos los primeros primer\u00edsimos en llegar.<br>En medio de la carretera, cerca de la puerta de entrada a la terminal, vimos a un grupo de personas que parec\u00edan trabajadores, as\u00ed que les preguntamos si sab\u00edan qu\u00e9 ten\u00edamos que hacer y nos se\u00f1alaron nuestras maletas. Sin estar seguros de estar haciendo lo correcto, dejamos nuestras maletas bajo la lluvia a su recaudo y nos entramos a la terminal.<\/p>\n\n\n\n<p>Afortunadamente, hab\u00eda un Starbucks en la terminal de cruceros, el cual, me aliment\u00f3 durante las 6h en las que estuvimos esperando a embarcar.<\/p>\n\n\n\n<p>Una vez a bordo, nos desped\u00edamos del destino m\u00e1s agridulce que hemos tenido el honor de visitar, pero ya pensando en volver, para visitar los Guerreros de Xian y volvernos a pasar por el mercado de las falsificaciones.<\/p>\n\n\n\n<p>Especialmente visitando China (que es la cultura m\u00e1s diferente, que hemos tenido la oportunidad de visitar hasta ahora) y viviendo muchas situaciones diferentes e incre\u00edbles, nos hizo recordar que:<br>&#8211; lo que consideras una &#8220;cosa normal&#8221;, no lo es para todos,<br>&#8211; lo que entiendes como un manjar, no lo es para todos,<br>&#8211; y lo que consideras insoportable, es algo que otros, ni siquiera se plantean.<br>Todo depende de lo que has visto, experimentado y vivido durante toda tu vida y todos esos factores son los que crean la idea de &#8220;tus cosas normales&#8221;.<br>Cuando viajas, todas esas cosas que se salen de tu idea de &#8220;lo normal&#8221; se te aparecer\u00e1n constantemente record\u00e1ndote que debes ser abierto, disfrutar de los h\u00e1bitos de los dem\u00e1s y lo m\u00e1s importante, aprender a respetar otras culturas.<br>Porque, aunque te puede resultar extra\u00f1o, sorprendente, inc\u00f3modo o fabuloso, es su &#8220;cosa normal&#8221; y siendo un invitado, te ofrecen el mejor de los regalos, la posibilidad de ser uno de ellos o vivir tal y como ellos lo hacen durante el tiempo que est\u00e1s visitando su hogar y tambi\u00e9n a lo mejor, la posibilidad de llegar a considerar otras cosas como &#8220;cosas normales&#8221;.<\/p>\n\n\n\n<h2 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"informacion-util\"><span class=\"ez-toc-section\" id=\"Informacion_Util\"><\/span>Informaci\u00f3n \u00datil<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-background has-fixed-layout\" style=\"background-color:#fcf0ef\"><tbody><tr><td><strong>Moneda: <\/strong>Renminbi\/Yuan CNY<\/td><td><strong>Tipo de Turismo:<\/strong> Ciudad<\/td><td><strong>Agua potable:<\/strong> No<\/td><\/tr><tr><td><strong>Temperatura:<\/strong> 15\u00baC en abril<\/td><td><strong>Coste Medio:<\/strong> 2\/5<\/td><td><strong>Lado de conducci\u00f3n: <\/strong>Derecha<\/td><\/tr><tr><td><strong>Zona Horaria: <\/strong>UTC\/GMT +8<\/td><td><strong>Tipo de Enchufe:<\/strong> Tipo I<\/td><td><strong>Modo de Transporte:<\/strong> Metro<\/td><\/tr><tr><td><strong>Poblaci\u00f3n:<\/strong> +- 24.3 Millones<\/td><td><strong>Visado?:<\/strong> Si<\/td><td><strong>Seguridad:<\/strong> 4\/5<\/td><\/tr><tr><td><strong>Idiomas:<\/strong> Shanghain\u00e9s\/Mandar\u00edn<\/td><td><strong>Apto para Vegetarianos:<\/strong> 1\/5<\/td><td><strong>Apto para viajes con ni\u00f1os:<\/strong> Si<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"has-trawell-cat-2-color has-text-color wp-block-heading\" id=\"consejos\"><span class=\"ez-toc-section\" id=\"Consejos\"><\/span>Consejos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Cuando viajes a China, tienes que ser consciente de que la cultura china es completamente diferente a la nuestra.<\/p>\n\n\n\n<ul class=\"is-style-checkbox wp-block-list\"><li>Algunas de las ciudades como Shanghai, tienen m\u00e1s de 24 millones de habitantes, es una metr\u00f3polis tan grande que ni somos conscientes de cuanto. Para hacerte una idea, de una parada de metro a la siguiente, puedes andar a paso r\u00e1pido durante casi una hora.<\/li><li>Siendo occidental, ser\u00e1s el centro de atenci\u00f3n en todos los lugares a los que vayas y todos te mirar\u00e1n: personas mayores, ni\u00f1os, mujeres y hombres&#8230; e incluso te har\u00e1n fotos. A pesar de ser tantos habitantes, no se ven a penas occidentales, por lo que para ellos, es todo un evento.<\/li><li>Comer en China es como comer en esos restaurantes donde cenas en la absoluta oscuridad, nunca sabr\u00e1s lo que est\u00e1s comiendo y, aunque preguntes, es probable que nunca recibas una respuesta (de nuevo, esto no es de mala educaci\u00f3n para ellos).<\/li><li>Mientras caminas por la calle te encontrar\u00e1s con personas que escupir\u00e1n en el suelo, gente eructando&#8230; Son comportamientos socialmente aceptados para ellos. En los centros comerciales de lujo, estaba prohibido, pero a\u00fan as\u00ed segu\u00eda sucediendo.<\/li><li>Los habitantes usar\u00e1n m\u00e1scaras cuando ellos est\u00e9n refriados y con el fin de no contagiarlo, nos pareci\u00f3 muy buena idea, pero era algo que antes del COVID19, era inusual para nosotros los occidentales),<\/li><li>Es muy com\u00fan que el inodoro sea una letrina y cuando finalmente encuentres inodoros como los que nosotros usamos, ver\u00e1s que el asiento est\u00e1 lleno de huellas de zapatos, porque a pesar de que no es una letrina, todav\u00eda lo usar\u00e1n de esa manera.<\/li><li>En Shangh\u00e1i, buscamos incansablemente una postal y m\u00e1s tarde nos dijeron que solo las puedes encontrar junto con los souvenirs en el barrio de Yuyuan.<\/li><li>En China, no hablan ingl\u00e9s en absoluto, ni siquiera en lugares muy tur\u00edsticos.<\/li><li>Negocia, negocia y negocia.<\/li><li>Google Maps es una de las aplicaciones prohibidas en China (junto con Facebook), por lo que te recomendamos descargar los mapas para que puedan ser usados sin conexi\u00f3n si planeas hacer turismo por tu cuenta.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Este fue el comienzo de nuestra luna de miel. A Josh le hac\u00eda mucha ilusi\u00f3n ir a Asia y yo acced\u00ed, pero solo si lo visit\u00e1bamos en un crucero. Nuestro viaje dur\u00f3 poco menos de un mes y visitamos: China, Corea del Sur, la isla de Jeju, Jap\u00f3n, Taiw\u00e1n y Hong Kong.China es el lugar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[116],"tags":[138,132],"class_list":["post-1169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia_es","tag-china","tag-que-hacer-2"],"_links":{"self":[{"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/posts\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":9,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/posts\/1169\/revisions"}],"predecessor-version":[{"id":4496,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/posts\/1169\/revisions\/4496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/media\/917"}],"wp:attachment":[{"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/categories?post=1169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thelittlerstravel.com\/es\/wp-json\/wp\/v2\/tags?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}